{"id":3,"date":"2018-07-25T10:51:29","date_gmt":"2018-07-25T10:51:29","guid":{"rendered":"https:\/\/restaurantelarustica.com\/pizzaypasta\/?page_id=3"},"modified":"2020-11-11T12:09:01","modified_gmt":"2020-11-11T12:09:01","slug":"politica-privacidad","status":"publish","type":"page","link":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<style type=\"text\/css\"><\/style><h3>AVISO LEGAL Y CONDICIONES DE USO<\/h3>\n<p>El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d)\u00a0implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso,\u00a0teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado.<\/p>\n<p>Su observancia y cumplimiento ser\u00e1 exigible respecto de cualquier persona que acceda, navegue o utilice\u00a0el Sitio Web. Si Ud. no est\u00e1 de acuerdo con los t\u00e9rminos expuestos, no acceda, navegue o utilice el Sitio\u00a0Web.<\/p>\n<h4>1 IDENTIFICACI\u00d3N<\/h4>\n<p>\u2022 Titular: RUSPAGOL,S.L.<br \/>\n\u2022 Domicilio social: Avenida Papagayo 67-69 , 35580 , Playa Blanca ,Las Palmas , Espa\u00f1a.<br \/>\n\u2022 CIF: B-76304773.<br \/>\n\u2022 Registro P\u00fablico: Tomo: 493 Libro : 0 Folio : 139 Secci\u00f3n : 8 Hoja : IL12014.<br \/>\n\u2022 Tel\u00e9fono y Fax: 928-349 390.<br \/>\n\u2022 E-mail: info@restaurantelarustica.com<\/p>\n<h4>2 OBJETO<\/h4>\n<p>Las presentes Condiciones de Uso regulan el acceso, navegaci\u00f3n y utilizaci\u00f3n del presente Sitio Web, sin\u00a0perjuicio de que el prestador se reserva el derecho a modificar la presentaci\u00f3n, configuraci\u00f3n y contenido\u00a0del mismo, as\u00ed como las condiciones requeridas para su acceso y\/o utilizaci\u00f3n. El acceso y utilizaci\u00f3n de los\u00a0contenidos del Sitio Web tras la entrada en vigor de sus modificaciones o cambios suponen la aceptaci\u00f3n\u00a0de los mismos.<\/p>\n<p>No obstante, el acceso a determinados contenidos y la utilizaci\u00f3n de determinados servicios puede\u00a0encontrarse sometido a determinadas condiciones particulares, que ser\u00e1n en todo caso claramente\u00a0mostradas y deber\u00e1n ser aceptadas expresamente por parte de los usuarios. Estas condiciones particulares\u00a0podr\u00e1n sustituir, completar o, en su caso, modificar las presentes Condiciones de Uso.<\/p>\n<p>El prestador se reserva el derecho a modificar los t\u00e9rminos y condiciones aqu\u00ed estipulados, total o\u00a0parcialmente, publicando cualquier cambio en la misma forma en que aparecen estas Condiciones de Uso\u00a0o a trav\u00e9s de cualquier tipo de comunicaci\u00f3n dirigida a los usuarios.<\/p>\n<p>Del mismo modo, informamos a los usuarios acerca de cu\u00e1les son sus derechos y sus obligaciones en\u00a0relaci\u00f3n con los contenidos expuestos a trav\u00e9s del Sitio Web, logotipos y marcas utilizadas, as\u00ed como las\u00a0responsabilidades que pueden derivarse del uso del servicio.<\/p>\n<p>A los efectos de la interpretaci\u00f3n de las presentes Condiciones de Uso, entendemos que una persona pasa\u00a0a ser usuaria en el momento en que \u00e9sta acepta las Condiciones de Uso y la Pol\u00edtica de Privacidad expuestas\u00a0en el Sitio Web, bastando para ello que lo visite.<\/p>\n<h4>3 DERECHOS DE PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h4>\n<p>El prestador es titular o, en su caso, cuenta con las licencias correspondientes sobre los derechos de\u00a0explotaci\u00f3n de propiedad intelectual e industrial del Sitio Web, as\u00ed como de todos los contenidos ofrecidos\u00a0en el mismo, incluyendo la propia plataforma, textos, fotograf\u00edas o ilustraciones, logos, marcas, grafismos,\u00a0dise\u00f1os, interfaces, o cualquier otra informaci\u00f3n o contenido, y los servicios disponibles a trav\u00e9s del mismo.<\/p>\n<p>En ning\u00fan caso se entender\u00e1 que el acceso, navegaci\u00f3n y utilizaci\u00f3n del Sitio Web por parte del usuario o\u00a0la utilizaci\u00f3n, adquisici\u00f3n y\/o contrataci\u00f3n de productos o servicios ofertados a trav\u00e9s del mismo implica\u00a0una renuncia, transmisi\u00f3n, licencia o cesi\u00f3n total o parcial de dichos derechos por parte del prestador. El\u00a0usuario dispone de un derecho de uso de los contenidos y\/o servicios del Sitio Web dentro de un \u00e1mbito\u00a0estrictamente dom\u00e9stico y \u00fanicamente con la finalidad de disfrutar de las prestaciones del servicio de\u00a0acuerdo con las presentes Condiciones de Uso.<\/p>\n<p>Las referencias a marcas o nombres comerciales registrados, u otros signos distintivos, ya sean titularidad\u00a0del prestador o de terceras empresas, llevan impl\u00edcita la prohibici\u00f3n sobre su uso sin el consentimiento del\u00a0prestador o de sus leg\u00edtimos titulares. En ning\u00fan momento, salvo manifestaci\u00f3n expresa en contrario, el\u00a0acceso, navegaci\u00f3n o utilizaci\u00f3n del Sitio Web y\/o de sus contenidos confiere al usuario derecho alguno\u00a0sobre signos distintivos en \u00e9l incluidos.<\/p>\n<p>Quedan reservados todos los derechos de propiedad intelectual e industrial sobre los contenidos y\/o\u00a0servicios del Sitio Web y, en particular, queda prohibido modificar, copiar, reproducir, comunicar\u00a0p\u00fablicamente, transformar o distribuir, por cualquier medio y bajo cualquier forma, la totalidad o parte de\u00a0los contenidos incluidos en el Sitio Web, para prop\u00f3sitos p\u00fablicos o comerciales, si no se cuenta con la\u00a0autorizaci\u00f3n previa, expresa y por escrito del prestador o, en su caso, del titular de los derechos<br \/>\ncorrespondientes.<\/p>\n<p>Asimismo, queda prohibido suprimir o manipular las indicaciones de copyright u otros cr\u00e9ditos que\u00a0identifiquen a los titulares de derechos de los contenidos que el usuario encuentre en el Sitio Web, as\u00ed\u00a0como los dispositivos t\u00e9cnicos de protecci\u00f3n, las huellas digitales, o cualquier mecanismo de protecci\u00f3n o\u00a0informaci\u00f3n incorporada a los contenidos ofrecidos en el Sitio Web.\u00a0En el caso de que el usuario env\u00ede informaci\u00f3n de cualquier tipo al prestador a trav\u00e9s de cualquiera de los\u00a0canales habilitados al efecto, el usuario declara, garantiza y acepta que tiene derecho a hacerlo libremente,\u00a0que dicha informaci\u00f3n no infringe ning\u00fan derecho de propiedad intelectual, industrial, secreto comercial o\u00a0cualesquiera otros derechos de terceros, y que dicha informaci\u00f3n no tiene car\u00e1cter confidencial ni es\u00a0perjudicial para terceros.<\/p>\n<p>El usuario reconoce asumir la responsabilidad, dejando indemne al prestador por cualquier comunicaci\u00f3n\u00a0que suministre personalmente o a su nombre, alcanzando dicha responsabilidad sin restricci\u00f3n alguna la\u00a0exactitud, legalidad, originalidad y titularidad de la misma.<\/p>\n<p>Si el usuario tuviera conocimiento de la existencia de alg\u00fan contenido il\u00edcito, ilegal, contrario a las leyes o\u00a0que pudiera suponer una infracci\u00f3n de derechos de propiedad intelectual y\/o industrial, deber\u00e1 notificarlo\u00a0inmediatamente al prestador a trav\u00e9s de la direcci\u00f3n de correo electr\u00f3nico info@restaurantelarustica.com\u00a0para que \u00e9sta pueda proceder a la adopci\u00f3n de las medidas oportunas.<\/p>\n<p>De igual modo, en el caso de que cualquier usuario o un tercero consideren que alguno de los contenidos\u00a0del Sitio Web propiedad del prestador vulnera sus derechos de propiedad intelectual y\/o industrial, as\u00ed\u00a0como cualesquiera otros derechos, deber\u00e1 remitir una comunicaci\u00f3n a info@restaurantelarustica.com con\u00a0la siguiente informaci\u00f3n:<br \/>\n&#8211; Datos identificativos y medio de contacto del reclamante o de su representante legal.<br \/>\n&#8211; Documentaci\u00f3n que acredite su condici\u00f3n de titular de los derechos supuestamente infringidos.<br \/>\n&#8211; Relato detallado de los derechos supuestamente infringidos por el prestador, as\u00ed como su\u00a0localizaci\u00f3n exacta dentro del Sitio Web.<br \/>\n&#8211; Declaraci\u00f3n expresa por parte del reclamante de que la utilizaci\u00f3n de los contenidos se ha realizado\u00a0sin el consentimiento del titular de los derechos supuestamente infringidos.<\/p>\n<h4>4 ENLACES<\/h4>\n<h5>4.1. ENLACES A OTRAS P\u00c1GINAS WEB<\/h5>\n<p>En caso de que en el Sitio Web se mostraran enlaces a otras p\u00e1ginas web mediante diferentes botones,\u00a0links, banners o contenidos embebidos, el prestador informa que \u00e9stos se encuentran directamente\u00a0gestionados por terceros, no teniendo el prestador ni medios humanos ni t\u00e9cnicos para conocer de forma\u00a0previa y\/o controlar y\/o aprobar toda la informaci\u00f3n, contenidos, productos o servicios facilitados por otras\u00a0plataformas a las que se puedan establecer enlaces desde el Sitio Web.<\/p>\n<p>En consecuencia, el prestador no podr\u00e1 asumir ning\u00fan tipo de responsabilidad por cualquier aspecto relativo\u00a0a la plataforma o p\u00e1gina web a la que se pudiera establecer un enlace desde el Sitio Web, en concreto, a\u00a0t\u00edtulo enunciativo y no limitativo, sobre su funcionamiento, acceso, datos, informaci\u00f3n, archivos, calidad y\u00a0fiabilidad de sus productos y servicios, sus propios enlaces y\/o cualquiera de sus contenidos, en general.<\/p>\n<p>En este sentido, si los usuarios tuvieran conocimiento efectivo de que las actividades desarrolladas a trav\u00e9s\u00a0de estas p\u00e1ginas web de terceros son ilegales o contravienen la moral y\/o el orden p\u00fablico, deber\u00e1n\u00a0comunicarlo inmediatamente al prestador a los efectos de que se proceda a deshabilitar el enlace de acceso\u00a0a las mismas, acci\u00f3n que se llevar\u00e1 a cabo en el menor tiempo posible.<\/p>\n<p>En cualquier caso, el establecimiento de cualquier tipo de enlace desde el Sitio Web a otra p\u00e1gina web\u00a0ajena no implicar\u00e1 que exista alg\u00fan tipo de relaci\u00f3n, colaboraci\u00f3n o dependencia entre el prestador y el\u00a0responsable de dicha p\u00e1gina web ajena.<\/p>\n<h5>4.2. ENLACES AL CANAL DEL PRESTADOR EN OTRAS PLATAFORMAS Y REDES SOCIALES<\/h5>\n<p>El prestador pone a disposici\u00f3n de los usuarios, a trav\u00e9s de diferentes herramientas y aplicaciones, medios\u00a0de enlace que permiten a los usuarios acceder a los canales y p\u00e1ginas del Sitio Web que el prestador\u00a0mantiene en diferentes plataformas y redes sociales pertenecientes y\/o gestionadas por terceros (p.ej.\u00a0Facebook, Twitter, Pinterest, Google+, etc.). La inclusi\u00f3n de estos enlaces en el Sitio Web tiene por \u00fanico\u00a0objeto facilitar a los usuarios el acceso a dichos canales en las diferentes plataformas y redes sociales.<\/p>\n<p>El establecimiento de estas aplicaciones no implica la existencia de relaci\u00f3n alguna entre el prestador y el\u00a0titular, fabricante o distribuidor de la plataforma enlazada, como tampoco la aceptaci\u00f3n y aprobaci\u00f3n por\u00a0parte del prestador de sus contenidos y\/o servicios, siendo su titular, fabricante o distribuidor el \u00fanico\u00a0responsable de los mismos.<br \/>\nEn ning\u00fan caso el prestador comparte con Facebook, Twitter o cualquier otra red social que se incorpore\u00a0en el futuro ning\u00fan tipo de informaci\u00f3n privada sobre sus usuarios, siendo su \u00fanica finalidad la establecida\u00a0en las presentes Condiciones de Uso, as\u00ed como en la Pol\u00edtica de Privacidad del Sitio Web. En este sentido,\u00a0toda la informaci\u00f3n que el propio usuario desee proporcionar a estas plataformas ser\u00e1 bajo su propia\u00a0responsabilidad, no interviniendo el prestador en dicho proceso.<\/p>\n<p>La activaci\u00f3n y uso de estas aplicaciones puede conllevar la identificaci\u00f3n y autenticaci\u00f3n del usuario\u00a0(login\/contrase\u00f1a) en las plataformas correspondientes, completamente externas al Sitio Web y fuera del\u00a0control del prestador. Al acceder a dichas redes externas, el usuario ingresa en un entorno no controlado\u00a0por el prestador, por lo que el prestador no asumir\u00e1 ninguna responsabilidad sobre la configuraci\u00f3n de\u00a0seguridad de dichos entornos.<\/p>\n<p>Dado que el prestador no tiene control alguno sobre el contenido alojado en dichos canales, el usuario\u00a0reconoce y acepta que el prestador no asume responsabilidad alguna por el contenido ni por los servicios\u00a0a los que el usuario pueda acceder en dichas p\u00e1ginas, ni por cualquier contenido, productos, servicios,\u00a0publicidad, ni cualquier otro material disponible en los mismos. Por tal motivo, el usuario debe extremar la\u00a0prudencia en la valoraci\u00f3n y utilizaci\u00f3n de la informaci\u00f3n, contenidos y servicios existentes en los canales\u00a0enlazados, y sobre la informaci\u00f3n propia o de terceros que quiera compartir en dichos canales.<\/p>\n<h5>4.3. ENLACES EN OTRAS P\u00c1GINAS WEB CON DESTINO AL SITIO WEB<\/h5>\n<p>El prestador no autoriza el establecimiento de un enlace al Sitio Web desde aquellas p\u00e1ginas que contengan\u00a0materiales, informaci\u00f3n o contenidos il\u00edcitos, ilegales, degradantes, obscenos y, en general, que\u00a0contravengan las leyes, la moral o el orden p\u00fablico, o las normas sociales generalmente aceptadas.<\/p>\n<p>En todo caso, los usuarios podr\u00e1n establecer enlaces en sus respectivas p\u00e1ginas web que dirijan al Sitio\u00a0Web, siempre y cuando cumplan con las siguientes condiciones: a) el enlace no podr\u00e1 reproducir el\u00a0contenido del Sitio Web o partes del mismo de ninguna forma; b) no est\u00e1 permitido crear un browser ni un\u00a0border environment sobre las secciones del Sitio Web, ni de ninguna otra forma podr\u00e1 modificarse el Sitio\u00a0Web; c) no est\u00e1 permitido realizar manifestaciones o indicaciones falsas o inexactas o incorrectas sobre el\u00a0Sitio Web y\/o, en particular, declarar o dar a entender que el prestador ha autorizado el enlace o que ha\u00a0supervisado o asumido de cualquier forma los contenidos o servicios ofrecidos o puestos a disposici\u00f3n en\u00a0la p\u00e1gina web en la que se establece dicho enlace; d) la p\u00e1gina web en la que se establezca el enlace al<br \/>\nSitio Web no contendr\u00e1 informaciones o contenidos il\u00edcitos, contrarios a la moral y buenas costumbres\u00a0generalmente aceptadas y al orden p\u00fablico, as\u00ed como tampoco contendr\u00e1 contenidos contrarios a\u00a0cualesquiera derechos de terceros, incluidos los derechos de propiedad intelectual e industrial y\/o el\u00a0derecho al honor, a la intimidad personal o familiar o a la propia imagen o de cualquier otro derecho, o\u00a0contenidos contrarios a las normas reguladoras de la protecci\u00f3n de datos de car\u00e1cter personal.<br \/>\nEl prestador no tiene facultad ni medios humanos ni t\u00e9cnicos para conocer, controlar ni aprobar toda la\u00a0informaci\u00f3n, contenidos, productos o servicios facilitados por otras p\u00e1ginas web que tengan establecidos\u00a0enlaces con destino al Sitio Web. El prestador no asume ning\u00fan tipo de responsabilidad por cualquier\u00a0aspecto relativo a la p\u00e1gina web que establece ese enlace con destino al Sitio Web, en concreto, a t\u00edtulo\u00a0enunciativo y no taxativo, sobre su funcionamiento, acceso, datos, informaci\u00f3n, archivos, calidad y<br \/>\nfiabilidad de sus productos y servicios, sus propios enlaces y\/o cualquiera de sus contenidos, en general.<\/p>\n<h5>5 REGLAS DE USO DEL SITIO WEB<\/h5>\n<p>No est\u00e1 permitido y, por tanto, sus consecuencias ser\u00e1n de la exclusiva responsabilidad del usuario, el\u00a0acceso o la utilizaci\u00f3n del Sitio Web con fines ilegales o no autorizados, con o sin finalidad econ\u00f3mica. En\u00a0particular, y sin que el siguiente listado tenga car\u00e1cter absoluto, queda prohibido:<\/p>\n<p>1) Usar el Sitio Web en forma alguna que pueda provocar da\u00f1os, interrupciones, ineficiencias o\u00a0defectos en su funcionamiento o en el ordenador de un tercero;<br \/>\n2) Usar el Sitio Web para la transmisi\u00f3n, instalaci\u00f3n o publicaci\u00f3n de cualquier virus, c\u00f3digo malicioso\u00a0u otros programas o archivos perjudiciales;<br \/>\n3) Usar el Sitio Web para recoger datos de car\u00e1cter personal de otros usuarios;<br \/>\n4) Usar el Sitio Web de forma ilegal, en contra de la buena fe, la moral y el orden p\u00fablico;<br \/>\n5) Registrarse a trav\u00e9s del Sitio Web con una identidad falsa, suplantando a terceros o utilizando un\u00a0perfil o realizando cualquier otra acci\u00f3n que pueda confundir a otros usuarios sobre la identidad del\u00a0origen de un mensaje;<br \/>\n6) Acceder sin autorizaci\u00f3n a cualquier secci\u00f3n del Sitio Web, a otros sistemas o redes conectados al\u00a0Sitio Web, a ning\u00fan servidor del prestador, ni a los servicios ofrecidos a trav\u00e9s del Sitio Web, por\u00a0medio de pirateo o falsificaci\u00f3n, extracci\u00f3n de contrase\u00f1as o cualquier otro medio ileg\u00edtimo;<br \/>\n7) Quebrantar, o intentar quebrantar, las medidas de seguridad o autenticaci\u00f3n del Sitio Web o de\u00a0cualquier red conectada al mismo, o las medidas de seguridad o protecci\u00f3n inherentes a los\u00a0contenidos ofrecidos en el Sitio Web;<br \/>\n8) Llevar a cabo alguna acci\u00f3n que provoque una saturaci\u00f3n desproporcionada o innecesaria en la\u00a0infraestructura del Sitio Web o en los sistemas o redes del prestador, as\u00ed como en los sistemas y\u00a0redes conectados al Sitio Web; o<br \/>\n9) Impedir el normal desarrollo de un evento, concurso, promoci\u00f3n o cualquier otra actividad\u00a0disponible a trav\u00e9s del Sitio Web o cualesquiera de sus funcionalidades, ya sea alterando o tratando\u00a0de alterar, ilegalmente o de cualquier otra forma, el acceso, participaci\u00f3n o funcionamiento de\u00a0aqu\u00e9llos, o falseando el resultado de los mismos y\/o utilizando m\u00e9todos de participaci\u00f3n\u00a0fraudulentos, mediante cualquier procedimiento, y\/o a trav\u00e9s de cualquier pr\u00e1ctica que atente o\u00a0vulnere en modo alguno las presentes Condiciones de Uso.<\/p>\n<p>El incumplimiento de cualquiera de las anteriores obligaciones por el usuario podr\u00e1 llevar aparejada la\u00a0adopci\u00f3n por el prestador de las medidas oportunas amparadas en Derecho y en el ejercicio de sus derechos\u00a0u obligaciones, pudiendo llegar a la eliminaci\u00f3n o bloqueo de la cuenta del usuario infractor, sin que medie\u00a0posibilidad de indemnizaci\u00f3n alguna por los da\u00f1os y perjuicios causados.<\/p>\n<p>Del mismo modo, el Sitio Web cuenta con \u00e1reas a trav\u00e9s de las que los usuarios pueden participar, publicar\u00a0contenidos propios y\/o compartir contenidos, propios o publicados por el prestador. Dichas \u00e1reas pueden\u00a0ser propias del prestador y por tanto dependientes y controladas por \u00e9sta, o ajenas al prestador, trat\u00e1ndose<br \/>\nde redes sociales independientes y ajenas a nuestra organizaci\u00f3n, respecto de las que no podemos\u00a0responsabilizarnos, ni del correcto funcionamiento, ni de las condiciones y pol\u00edticas dispuestas por sus\u00a0responsables, siendo el propio usuario quien deber\u00e1 consentir y asumir en todo momento el tratamiento\u00a0que se realice de la informaci\u00f3n publicada en dichas plataformas.<\/p>\n<p>En todo caso, le informamos que cuando el usuario participe en cualquiera de estas zonas, el resto de\u00a0usuarios del Sitio Web podr\u00e1 acceder y utilizar todos los contenidos publicados por el usuario. El prestador\u00a0no puede controlar qu\u00e9 uso realizar\u00e1n otras personas de esos contenidos y, por tanto, el prestador no se\u00a0hace responsable de ello. El prestador le recomienda que no publique datos de car\u00e1cter personal o\u00a0materiales protegidos por derechos de propiedad intelectual e industrial o cualesquiera otros derechos.<\/p>\n<p>Con el fin de que el Sitio Web sea un entorno seguro, y para proteger a nuestros usuarios, queda\u00a0terminantemente prohibido publicar contenidos:<br \/>\n1) Que puedan ser considerados como una vulneraci\u00f3n en cualquier forma de los derechos\u00a0fundamentales al honor, a la intimidad personal y familiar o a la propia imagen de terceros y, muy\u00a0especialmente, de los menores de edad;<br \/>\n2) Que incluyan fotograf\u00edas que recojan im\u00e1genes o datos personales de terceros sin haber obtenido\u00a0el oportuno consentimiento de sus titulares;<br \/>\n3) Que vulneren el secreto de las comunicaciones o que supongan una infracci\u00f3n de derechos de\u00a0propiedad intelectual e industrial o de las normas reguladoras de la protecci\u00f3n de datos de car\u00e1cter\u00a0personal;<br \/>\n4) Que contengan cualquier material o informaci\u00f3n que sea ilegal, racista, obscena, pornogr\u00e1fica,\u00a0abusiva, difamatoria, enga\u00f1osa, fraudulenta o de cualquier forma contraria a la moral o al orden\u00a0p\u00fablico;<br \/>\n5) Que contengan \u201cspam\u201d y\/o enlaces a sitios sin relaci\u00f3n con el espacio correspondiente;<br \/>\n6) Que incluyan publicidad o comunicaciones comerciales, para la emisi\u00f3n de mensajes con finalidad\u00a0publicitaria o para la captaci\u00f3n de datos con el mismo fin.<\/p>\n<p>El usuario que incumpla estas prohibiciones ser\u00e1 responsable de cualquier reclamaci\u00f3n que se produzca\u00a0como consecuencia de ello. Aunque no se produjera ninguna reclamaci\u00f3n de un tercero, el prestador se\u00a0reserva la posibilidad de impedir el acceso al Sitio Web o de la posibilidad de participar en los espacios\u00a0habilitados en el mismo a los usuarios que incumplan estas condiciones.<\/p>\n<p>El prestador no controla el contenido publicado por los usuarios en el Sitio Web y no asume responsabilidad\u00a0alguna por estos contenidos. No obstante, el prestador se reserva la posibilidad de supervisar y\/o moderar\u00a0cualquier contenido publicado por los usuarios y, en caso de que \u00e9ste vulnere las presentes Condiciones de\u00a0Uso o la Pol\u00edtica de Privacidad , de editarlo o eliminarlo. Asimismo, si Ud. encuentra alguna informaci\u00f3n o\u00a0contenido en el Sitio Web que pueda ser no adecuado, contrario a la normativa vigente, o contrario a las\u00a0condiciones dispuestas en el Sitio Web, rogamos que lo ponga en conocimiento inmediato del prestador a\u00a0trav\u00e9s de los diferentes medios dispuestos para ello.<\/p>\n<h5>6 RESPONSABILIDADES Y GARANT\u00cdAS<\/h5>\n<p>El prestador no puede garantizar la fiabilidad, utilidad o veracidad de absolutamente toda la informaci\u00f3n\u00a0y\/o de los servicios del Sitio Web, ni tampoco de la utilidad o veracidad de la documentaci\u00f3n puesta a\u00a0disposici\u00f3n a trav\u00e9s del mismo.<\/p>\n<p>En consecuencia, el prestador no garantiza ni se hace responsable de: (i) la continuidad de los contenidos\u00a0del Sitio Web; (ii) la ausencia de errores en dichos contenidos; (iii) la ausencia de virus y\/o dem\u00e1s\u00a0componentes da\u00f1inos en el Sitio Web o en el servidor que lo suministra; (iv) la invulnerabilidad del Sitio\u00a0Web y\/o la imposibilidad de vulnerar las medidas de seguridad que se adopten en el mismo; (v) la falta de\u00a0utilidad o rendimiento de los contenidos del Sitio Web; y (vi) los da\u00f1os o perjuicios que cause, a s\u00ed mismo\u00a0o a un tercero, cualquier persona que infringiera las condiciones, normas e instrucciones que el prestador\u00a0establece en el Sitio Web o a trav\u00e9s de la vulneraci\u00f3n de los sistemas de seguridad del Sitio Web.<\/p>\n<p>Ello no obstante, el prestador declara que ha adoptado todas las medidas necesarias, dentro de sus\u00a0posibilidades y del estado de la t\u00e9cnica, para garantizar el funcionamiento del Sitio Web y reducir al m\u00ednimo\u00a0los errores del sistema, tanto desde el punto de vista t\u00e9cnico como de los contenidos publicados en el Sitio<br \/>\nWeb.<\/p>\n<p>El prestador no garantiza la licitud, fiabilidad y utilidad de los contenidos suministrados por terceros a\u00a0trav\u00e9s del Sitio Web. Si el usuario tuviera conocimiento de la existencia de alg\u00fan contenido il\u00edcito, ilegal,\u00a0contrario a las leyes o que pudiera suponer una infracci\u00f3n de derechos de terceros, deber\u00e1 notificarlo\u00a0inmediatamente al prestador para que \u00e9sta pueda proceder a la adopci\u00f3n de las medidas oportunas.<\/p>\n<p>El prestador no ser\u00e1 responsable de la veracidad, integridad o actualizaci\u00f3n de las informaciones publicadas\u00a0en el Sitio Web provenientes de fuentes ajenas al mismo, as\u00ed como tampoco de las contenidas en otras\u00a0plataformas a las que se enlace desde el Sitio Web. El prestador no asumir\u00e1 responsabilidad en cuanto a\u00a0hipot\u00e9ticos perjuicios que pudieran originarse por el uso de las citadas informaciones.<\/p>\n<p>En todo caso, el prestador se reserva el derecho a suspender, modificar, restringir o interrumpir, ya sea\u00a0temporal o permanentemente, el acceso, navegaci\u00f3n, uso, alojamiento y\/o descarga del contenido y\/o uso\u00a0de servicios del Sitio Web, con o sin previa notificaci\u00f3n, a los usuarios que contravengan cualquiera de las<br \/>\ndisposiciones detalladas en las presentes Condiciones de Uso, sin que medie la posibilidad del usuario de\u00a0exigir indemnizaci\u00f3n alguna por esta causa.<\/p>\n<h5>7 SUSPENSI\u00d3N DEL SITIO WEB<\/h5>\n<p>El prestador se reserva el derecho a suspender, modificar, restringir o interrumpir, ya sea temporal o\u00a0permanentemente, el acceso, navegaci\u00f3n, uso, alojamiento y\/o descarga del contenido y\/o uso de servicios\u00a0del Sitio Web, con o sin previa notificaci\u00f3n, a los usuarios que contravengan cualquiera de las disposiciones<br \/>\ndetalladas en las presentes Condiciones de Uso, sin que medie la posibilidad del usuario de exigir\u00a0indemnizaci\u00f3n alguna por esta causa.<\/p>\n<h5>8 CONFIDENCIALIDAD Y PROTECCI\u00d3N DE DATOS<\/h5>\n<p>De conformidad con lo previsto en el Reglamento (UE) 2016\/679, de 27 de abril, los datos del\u00a0cliente\/usuario ser\u00e1n o podr\u00e1n ser incluidos en un fichero titularidad de Ruspagol,S.L. , B-76304773, con\u00a0sede en Av. Papagayo 67-69 , t\u00e9lf. 928349390, info@restaurantelarustica.com , y sin cuyo tratamiento no\u00a0ser\u00eda posible dar cumplimiento al contrato [art. 6.1.b) del Reglamento (UE) 2016\/679] o atender su\u00a0solicitud [art. 6.1.a) del Reglamento (UE) 2016\/679]. Dichos datos se tratar\u00e1n durante el periodo de<br \/>\nprestaci\u00f3n del servicio y se conservar\u00e1n durante los plazos de prescripci\u00f3n aplicables (que ser\u00edan de al\u00a0menos 5 a\u00f1os desde la \u00faltima acci\u00f3n de interesado).<br \/>\nPodr\u00e1n ser destinatarios de sus datos: proveedores, colaboradores u otras entidades que los precisen en\u00a0todo caso con objeto de atender las obligaciones del responsable y exigiendo un nivel de confidencialidad\u00a0equivalente.<\/p>\n<p>Los usuarios podr\u00e1n contactar con el delegado de protecci\u00f3n de datos, en su caso, o ejercitar los derechos\u00a0de acceso, rectificaci\u00f3n, oposici\u00f3n, supresi\u00f3n, limitaci\u00f3n, portabilidad u otros legalmente previstos a trav\u00e9s\u00a0de cualquiera de las direcciones indicadas, adjuntando copia de su DNI o documento identificativo an\u00e1logo.<br \/>\nEn caso de reclamaci\u00f3n, podr\u00e1n interponerla ante la autoridad de control competente (Agencia Espa\u00f1ola\u00a0de Protecci\u00f3n de Datos, www.agpd.es).<\/p>\n<h5>9 GENERALES<\/h5>\n<p>Los encabezamientos de las distintas cl\u00e1usulas son s\u00f3lo informativos, y no afectar\u00e1n, calificar\u00e1n o ampliar\u00e1n\u00a0la interpretaci\u00f3n de las presentes Condiciones de Uso. Asimismo, el prestador podr\u00e1 modificar los t\u00e9rminos\u00a0y condiciones aqu\u00ed estipulados, total o parcialmente, publicando cualquier cambio en la misma forma en<br \/>\nque aparecen estas Condiciones de Uso o a trav\u00e9s de cualquier tipo de comunicaci\u00f3n dirigida a los usuarios.<\/p>\n<p>La vigencia temporal de las presentes Condiciones de Uso coincide, por tanto, con el tiempo de su\u00a0exposici\u00f3n, hasta que sean modificadas total o parcialmente, momento en el cual pasar\u00e1n a tener vigencia\u00a0las Condiciones de Uso modificadas.<\/p>\n<p>Con independencia de lo dispuesto en las condiciones particulares que en su caso se establezcan, el\u00a0prestador podr\u00e1 dar por terminado, suspender o interrumpir, en cualquier momento y sin necesidad de\u00a0preaviso, el acceso a los contenidos del Sitio Web, sin posibilidad por parte del usuario de exigir\u00a0indemnizaci\u00f3n alguna. Tras dicha extinci\u00f3n, seguir\u00e1n vigentes las prohibiciones de uso de los contenidos\u00a0expuestas anteriormente en las presentes Condiciones de Uso.<\/p>\n<p>Asimismo, si el usuario incumple las presentes Condiciones de Uso, el prestador podr\u00e1 suspender o cancelar\u00a0su perfil autom\u00e1ticamente y sin previo aviso, y en ning\u00fan caso tal suspensi\u00f3n o cancelaci\u00f3n dar\u00eda al usuario\u00a0derecho a indemnizaci\u00f3n alguna. A estos efectos, el prestador informa de que podr\u00e1 poner en conocimiento\u00a0y colaborar oportunamente con las autoridades policiales y judiciales competentes si detectase cualquier\u00a0infracci\u00f3n de la legislaci\u00f3n vigente o si tuviera sospecha de la comisi\u00f3n de alg\u00fan delito.<\/p>\n<p>La contrataci\u00f3n de cualquier producto y\/o servicio de pago ofrecido por el prestador quedar\u00e1 regulada por\u00a0las condiciones generales y\/o particulares de cada servicio espec\u00edfico dispuestas al efecto.<\/p>\n<p>En el caso de existir discrepancia entre lo establecido en las presentes Condiciones de Uso y las condiciones\u00a0particulares de cada servicio espec\u00edfico del Sitio Web, prevalecer\u00e1 lo dispuesto en estas \u00faltimas.<\/p>\n<p>En el caso de que cualquier disposici\u00f3n de las presentes Condiciones de Uso fuese declarada nula o\u00a0inaplicable, en su totalidad o en parte, por cualquier Juzgado, Tribunal u \u00f3rgano administrativo competente,\u00a0dicha nulidad o inaplicaci\u00f3n no afectar\u00e1 a las restantes disposiciones de las presentes Condiciones de Uso.<\/p>\n<p>El no ejercicio o ejecuci\u00f3n por parte del prestador de cualquier derecho o disposici\u00f3n contenido en las\u00a0presentes Condiciones de Uso no constituir\u00e1 una renuncia al mismo, salvo reconocimiento y acuerdo por\u00a0escrito por su parte.<\/p>\n<h5>10 LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N COMPETENTE<\/h5>\n<p>Siempre que la normativa vigente al efecto prevea la posibilidad para las partes de someterse a un fuero\u00a0determinado, para toda cuesti\u00f3n litigiosa derivada o relacionada con este Sitio Web ser\u00e1 de aplicaci\u00f3n la\u00a0legislaci\u00f3n espa\u00f1ola vigente en el momento del litigio, y nos someteremos a los Juzgados y Tribunales de\u00a0Arrecife de Lanzarote , Las Palmas (salvo sumisi\u00f3n a distinto fuero por imperativo legal en contrario), as\u00ed\u00a0como, en su caso, a los Tribunales Arbitrales de consumo o semejantes a los que nos encontremos\u00a0adheridos en el momento de producirse la controversia.<\/p>\n<p>Para presentar reclamaciones en el uso de nuestros servicios, puede dirigirse por correo a la direcci\u00f3n\u00a0electr\u00f3nica o f\u00edsica indicada en el apartado \u201cIdentificaci\u00f3n\u201d, comprometi\u00e9ndonos a buscar en todo momento\u00a0una soluci\u00f3n amistosa del conflicto.<\/p>\n<p>\u00daltima actualizaci\u00f3n: Octubre 2018.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d)\u00a0implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso,\u00a0teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_joinchat":[],"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Restaurantes La R\u00fastica - La pizza artesanal favorita en Lanzarote\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica\" \/>\n\t\t<meta property=\"og:description\" content=\"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-25T10:51:29+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-11T12:09:01+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica\" \/>\n\t\t<meta name=\"twitter:description\" content=\"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/#listItem\",\"name\":\"Pol\\u00edtica de privacidad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de privacidad\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/#organization\",\"name\":\"La R\\u00fastica Pizza y Pasta\",\"description\":\"La pizza artesanal favorita en Lanzarote\",\"url\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/#webpage\",\"url\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/\",\"name\":\"Pol\\u00edtica de privacidad - Restaurantes La R\\u00fastica\",\"description\":\"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\\u00f3n y utilizaci\\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \\u201cSitio Web\\u201d) implica la aceptaci\\u00f3n expresa y sin reservas de todos los t\\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\\u00e1 exigible\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/politica-privacidad\\\/#breadcrumblist\"},\"datePublished\":\"2018-07-25T10:51:29+00:00\",\"dateModified\":\"2020-11-11T12:09:01+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/#website\",\"url\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/\",\"name\":\"La R\\u00fastica Pizza y Pasta\",\"description\":\"La pizza artesanal favorita en Lanzarote\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/restaurantelarustica.com\\\/pizzaypasta\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica","description":"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible","canonical_url":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta#listItem","position":1,"name":"Home","item":"https:\/\/restaurantelarustica.com\/pizzaypasta","nextItem":{"@type":"ListItem","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/#listItem","name":"Pol\u00edtica de privacidad"}},{"@type":"ListItem","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/#listItem","position":2,"name":"Pol\u00edtica de privacidad","previousItem":{"@type":"ListItem","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/#organization","name":"La R\u00fastica Pizza y Pasta","description":"La pizza artesanal favorita en Lanzarote","url":"https:\/\/restaurantelarustica.com\/pizzaypasta\/"},{"@type":"WebPage","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/#webpage","url":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/","name":"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica","description":"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/#website"},"breadcrumb":{"@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/#breadcrumblist"},"datePublished":"2018-07-25T10:51:29+00:00","dateModified":"2020-11-11T12:09:01+00:00"},{"@type":"WebSite","@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/#website","url":"https:\/\/restaurantelarustica.com\/pizzaypasta\/","name":"La R\u00fastica Pizza y Pasta","description":"La pizza artesanal favorita en Lanzarote","inLanguage":"es-ES","publisher":{"@id":"https:\/\/restaurantelarustica.com\/pizzaypasta\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Restaurantes La R\u00fastica - La pizza artesanal favorita en Lanzarote","og:type":"article","og:title":"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica","og:description":"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible","og:url":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/","article:published_time":"2018-07-25T10:51:29+00:00","article:modified_time":"2020-11-11T12:09:01+00:00","twitter:card":"summary_large_image","twitter:title":"Pol\u00edtica de privacidad - Restaurantes La R\u00fastica","twitter:description":"AVISO LEGAL Y CONDICIONES DE USO El acceso, navegaci\u00f3n y utilizaci\u00f3n del sitio web www.restaurantelarustica.com (en adelante, el \u201cSitio Web\u201d) implica la aceptaci\u00f3n expresa y sin reservas de todos los t\u00e9rminos de las presentes Condiciones de Uso, teniendo la misma validez y eficacia que cualquier contrato celebrado por escrito y firmado. Su observancia y cumplimiento ser\u00e1 exigible"},"aioseo_meta_data":{"post_id":"3","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-03-11 16:51:16","updated":"2025-06-26 11:34:27","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/restaurantelarustica.com\/pizzaypasta\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica de privacidad\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/restaurantelarustica.com\/pizzaypasta"},{"label":"Pol\u00edtica de privacidad","link":"https:\/\/restaurantelarustica.com\/pizzaypasta\/politica-privacidad\/"}],"_links":{"self":[{"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":5,"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":13166,"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/pages\/3\/revisions\/13166"}],"wp:attachment":[{"href":"https:\/\/restaurantelarustica.com\/pizzaypasta\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}